{"id":9726,"date":"2025-08-24T19:34:22","date_gmt":"2025-08-24T19:34:22","guid":{"rendered":"https:\/\/vescorp.bg\/?post_type=portfolio&#038;p=9726"},"modified":"2025-08-24T19:34:22","modified_gmt":"2025-08-24T19:34:22","slug":"hello-linen","status":"publish","type":"portfolio","link":"https:\/\/vescorp.bg\/en\/portfolio\/hello-linen\/","title":{"rendered":"Hello Linen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1481476949915 vc_row-o-equal-height vc_row-o-content-top vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-8 vc_col-md-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\t\t<div id=\"gallery_585\" class=\"wd-images-gallery wd-wpb wd-rs-68ab68da6126b photoswipe-images\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\n\t\t\t<div class=\"wd-grid-g\" style=\"--wd-col-lg:1;--wd-col-md:1;--wd-col-sm:1;--wd-gap-lg:30px;--wd-gap-sm:10px;\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/vescorp.bg\/vubirod\/2025\/08\/hl.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"800\" data-height=\"800\" \n\t\t\t\t\t\t\t\t\t\t\t\t >\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/vescorp.bg\/vubirod\/2025\/08\/hl.jpg\" class=\"wd-gallery-image image-1\" alt=\"\" srcset=\"https:\/\/vescorp.bg\/vubirod\/2025\/08\/hl.jpg 800w, https:\/\/vescorp.bg\/vubirod\/2025\/08\/hl-300x300.jpg 300w, https:\/\/vescorp.bg\/vubirod\/2025\/08\/hl-150x150.jpg 150w, https:\/\/vescorp.bg\/vubirod\/2025\/08\/hl-768x768.jpg 768w, https:\/\/vescorp.bg\/vubirod\/2025\/08\/hl-12x12.jpg 12w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_col-lg-4 vc_col-md-4 woodmart-sticky-column wd_sticky_offset_150\"><div class=\"vc_column-inner vc_custom_1494491003828\"><div class=\"wpb_wrapper\">\n\t\t<div id=\"wd-68ab68ec3e191\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-68ab68ec3e191 wd-title-color-default wd-title-style-default text-left vc_custom_1756063989059 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-400 wd-fontsize-xxl\" >Hello Linen<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t<div id=\"wd-68ab68f831ba1\" class=\"wd-text-block wd-wpb reset-last-child wd-rs-68ab68f831ba1 text-left wd-font-weight-400 wd-fontsize-s vc_custom_1756064032464\">\n\t\t\t<p>Website with linen rental e-commerce system.<\/p>\n\t\t<\/div>\n\t\t<div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_row-o-equal-height vc_row-o-content-middle vc_row-flex\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner vc_custom_1481476631480\"><div class=\"wpb_wrapper\"><div id=\"wd-68ab693114c23\" class=\"wd-rs-68ab693114c23  wd-button-wrapper text-left\"><a href=\"https:\/\/hellolinen.co.uk\/\" title=\"\" target=\"_blank\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-default btn-full-width\">VIEW ONLINE<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Hello Linen \u0423\u0435\u0431\u0441\u0430\u0439\u0442 \u0441\u044a\u0441 \u0441\u0438\u0442\u0435\u043c\u0430 \u0437\u0430 \u043e\u0442\u0434\u0430\u0432\u0430\u043d\u0435 \u043f\u043e\u0434 \u043d\u0430\u0435\u043c \u043d\u0430 \u0441\u043f\u0430\u043b\u043d\u043e \u0431\u0435\u043b\u044c\u043e. \u0412\u0418\u0416\u0422\u0415 \u041e\u041d\u041b\u0410\u0419\u041d","protected":false},"featured_media":9727,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","project-cat":[],"class_list":["post-9726","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/vescorp.bg\/en\/wp-json\/wp\/v2\/portfolio\/9726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vescorp.bg\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/vescorp.bg\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"replies":[{"embeddable":true,"href":"https:\/\/vescorp.bg\/en\/wp-json\/wp\/v2\/comments?post=9726"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vescorp.bg\/en\/wp-json\/wp\/v2\/media\/9727"}],"wp:attachment":[{"href":"https:\/\/vescorp.bg\/en\/wp-json\/wp\/v2\/media?parent=9726"}],"wp:term":[{"taxonomy":"project-cat","embeddable":true,"href":"https:\/\/vescorp.bg\/en\/wp-json\/wp\/v2\/project-cat?post=9726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}